{"id":21112,"date":"2022-08-16T15:05:05","date_gmt":"2022-08-16T18:05:05","guid":{"rendered":"https:\/\/saoluiz.uri.br\/wordpress\/?p=21112"},"modified":"2022-08-16T15:05:05","modified_gmt":"2022-08-16T18:05:05","slug":"uri-sediou-evento-sobre-os-desafios-da-advocacia-frente-a-adequacao-da-lei-geral-de-protecao-de-dados-no-brasil","status":"publish","type":"post","link":"https:\/\/saoluiz.uri.br\/wordpress\/index.php\/2022\/08\/16\/uri-sediou-evento-sobre-os-desafios-da-advocacia-frente-a-adequacao-da-lei-geral-de-protecao-de-dados-no-brasil\/","title":{"rendered":"URI sediou evento sobre &#8220;Os desafios da advocacia frente \u00e0 adequa\u00e7\u00e3o da Lei Geral de Prote\u00e7\u00e3o de Dados no Brasil&#8221;"},"content":{"rendered":"<p>Em 15 de agosto de 2022, ocorreu, no Sal\u00e3o de Atos da URI &#8211; S\u00e3o Luiz Gonzaga, evento promovido pela ESA-RS e pela OAB, Subse\u00e7\u00e3o local, com apoio do Curso de Direito.<\/p>\n<p>Tratou-se da palestra de t\u00edtulo &#8220;Os desafios da advocacia frente \u00e0 adequa\u00e7\u00e3o da Lei Geral de Prote\u00e7\u00e3o de Dados no Brasil&#8221;, proferida por Thami Covatti Piaia.<\/p>\n<p>Na abertura do evento, a OAB, Subse\u00e7\u00e3o local, fez a entrega \u00e0 professora Dinara Bortoli Tomasi de uma homenagem, pelos 30 anos da URI.<\/p>\n<p>Durante sua explana\u00e7\u00e3o, a palestrante apontou o conflito entre seguran\u00e7a e privacidade, referindo que, com a LGPD, \u00e9 chegado o momento de fazer valer o direito das pessoas a sua vida privada.<\/p>\n<p>Apresentou como se dar\u00e1 a prote\u00e7\u00e3o dos dados, a partir desta normativa, destacando as penalidades que ser\u00e3o arcadas por aqueles que a descumprirem.<\/p>\n<p>No final, respondeu diversas quest\u00f5es, que lhe foram encaminhadas pelo p\u00fablico.<\/p>\n<p>Agradecemos \u00e0 ESA-RS, \u00e0 OAB, Subse\u00e7\u00e3o local e \u00e0 palestrante, pela excelente noite de compartilhamento de conhecimento.<\/p>\n<p>Igualmente, agradecemos aos advogados, professores e acad\u00eamicos que se fizeram presentes.<\/p>\n<div id='gallery-1' class='gallery galleryid-21112 gallery-columns-3 gallery-size-medium'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/saoluiz.uri.br\/wordpress\/wp-content\/uploads\/2022\/08\/f4f98f27-1407-4bad-b5e4-416b87b341b0.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/saoluiz.uri.br\/wordpress\/wp-content\/uploads\/2022\/08\/f4f98f27-1407-4bad-b5e4-416b87b341b0-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/saoluiz.uri.br\/wordpress\/wp-content\/uploads\/2022\/08\/f4f98f27-1407-4bad-b5e4-416b87b341b0-300x200.jpg 300w, https:\/\/saoluiz.uri.br\/wordpress\/wp-content\/uploads\/2022\/08\/f4f98f27-1407-4bad-b5e4-416b87b341b0-1024x682.jpg 1024w, https:\/\/saoluiz.uri.br\/wordpress\/wp-content\/uploads\/2022\/08\/f4f98f27-1407-4bad-b5e4-416b87b341b0-768x512.jpg 768w, https:\/\/saoluiz.uri.br\/wordpress\/wp-content\/uploads\/2022\/08\/f4f98f27-1407-4bad-b5e4-416b87b341b0.jpg 1280w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/saoluiz.uri.br\/wordpress\/wp-content\/uploads\/2022\/08\/3ccb99c7-9b27-47d7-889a-97ce7d334970.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/saoluiz.uri.br\/wordpress\/wp-content\/uploads\/2022\/08\/3ccb99c7-9b27-47d7-889a-97ce7d334970-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/saoluiz.uri.br\/wordpress\/wp-content\/uploads\/2022\/08\/3ccb99c7-9b27-47d7-889a-97ce7d334970-300x200.jpg 300w, https:\/\/saoluiz.uri.br\/wordpress\/wp-content\/uploads\/2022\/08\/3ccb99c7-9b27-47d7-889a-97ce7d334970-1024x682.jpg 1024w, https:\/\/saoluiz.uri.br\/wordpress\/wp-content\/uploads\/2022\/08\/3ccb99c7-9b27-47d7-889a-97ce7d334970-768x512.jpg 768w, https:\/\/saoluiz.uri.br\/wordpress\/wp-content\/uploads\/2022\/08\/3ccb99c7-9b27-47d7-889a-97ce7d334970.jpg 1280w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/saoluiz.uri.br\/wordpress\/wp-content\/uploads\/2022\/08\/3499ed6e-23f1-42d6-9670-a69b486f275b.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/saoluiz.uri.br\/wordpress\/wp-content\/uploads\/2022\/08\/3499ed6e-23f1-42d6-9670-a69b486f275b-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/saoluiz.uri.br\/wordpress\/wp-content\/uploads\/2022\/08\/3499ed6e-23f1-42d6-9670-a69b486f275b-300x200.jpg 300w, https:\/\/saoluiz.uri.br\/wordpress\/wp-content\/uploads\/2022\/08\/3499ed6e-23f1-42d6-9670-a69b486f275b-1024x682.jpg 1024w, https:\/\/saoluiz.uri.br\/wordpress\/wp-content\/uploads\/2022\/08\/3499ed6e-23f1-42d6-9670-a69b486f275b-768x512.jpg 768w, https:\/\/saoluiz.uri.br\/wordpress\/wp-content\/uploads\/2022\/08\/3499ed6e-23f1-42d6-9670-a69b486f275b.jpg 1280w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/saoluiz.uri.br\/wordpress\/wp-content\/uploads\/2022\/08\/51014c85-48cf-461f-ab38-1c514433bd02.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/saoluiz.uri.br\/wordpress\/wp-content\/uploads\/2022\/08\/51014c85-48cf-461f-ab38-1c514433bd02-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/saoluiz.uri.br\/wordpress\/wp-content\/uploads\/2022\/08\/51014c85-48cf-461f-ab38-1c514433bd02-300x200.jpg 300w, https:\/\/saoluiz.uri.br\/wordpress\/wp-content\/uploads\/2022\/08\/51014c85-48cf-461f-ab38-1c514433bd02-1024x682.jpg 1024w, https:\/\/saoluiz.uri.br\/wordpress\/wp-content\/uploads\/2022\/08\/51014c85-48cf-461f-ab38-1c514433bd02-768x512.jpg 768w, https:\/\/saoluiz.uri.br\/wordpress\/wp-content\/uploads\/2022\/08\/51014c85-48cf-461f-ab38-1c514433bd02.jpg 1280w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/saoluiz.uri.br\/wordpress\/wp-content\/uploads\/2022\/08\/5a8e05b0-0cee-46b3-b9a5-1da2178c7cb9.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/saoluiz.uri.br\/wordpress\/wp-content\/uploads\/2022\/08\/5a8e05b0-0cee-46b3-b9a5-1da2178c7cb9-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/saoluiz.uri.br\/wordpress\/wp-content\/uploads\/2022\/08\/5a8e05b0-0cee-46b3-b9a5-1da2178c7cb9-300x200.jpg 300w, https:\/\/saoluiz.uri.br\/wordpress\/wp-content\/uploads\/2022\/08\/5a8e05b0-0cee-46b3-b9a5-1da2178c7cb9-1024x682.jpg 1024w, https:\/\/saoluiz.uri.br\/wordpress\/wp-content\/uploads\/2022\/08\/5a8e05b0-0cee-46b3-b9a5-1da2178c7cb9-768x512.jpg 768w, https:\/\/saoluiz.uri.br\/wordpress\/wp-content\/uploads\/2022\/08\/5a8e05b0-0cee-46b3-b9a5-1da2178c7cb9.jpg 1280w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/saoluiz.uri.br\/wordpress\/wp-content\/uploads\/2022\/08\/a5f23d89-b42e-4ccb-88b7-b8e17555e8de.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/saoluiz.uri.br\/wordpress\/wp-content\/uploads\/2022\/08\/a5f23d89-b42e-4ccb-88b7-b8e17555e8de-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/saoluiz.uri.br\/wordpress\/wp-content\/uploads\/2022\/08\/a5f23d89-b42e-4ccb-88b7-b8e17555e8de-300x200.jpg 300w, https:\/\/saoluiz.uri.br\/wordpress\/wp-content\/uploads\/2022\/08\/a5f23d89-b42e-4ccb-88b7-b8e17555e8de-1024x682.jpg 1024w, https:\/\/saoluiz.uri.br\/wordpress\/wp-content\/uploads\/2022\/08\/a5f23d89-b42e-4ccb-88b7-b8e17555e8de-768x512.jpg 768w, https:\/\/saoluiz.uri.br\/wordpress\/wp-content\/uploads\/2022\/08\/a5f23d89-b42e-4ccb-88b7-b8e17555e8de.jpg 1280w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/saoluiz.uri.br\/wordpress\/wp-content\/uploads\/2022\/08\/9b121487-a40d-46b9-a4f7-9c05ab5aef2b.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/saoluiz.uri.br\/wordpress\/wp-content\/uploads\/2022\/08\/9b121487-a40d-46b9-a4f7-9c05ab5aef2b-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/saoluiz.uri.br\/wordpress\/wp-content\/uploads\/2022\/08\/9b121487-a40d-46b9-a4f7-9c05ab5aef2b-300x200.jpg 300w, https:\/\/saoluiz.uri.br\/wordpress\/wp-content\/uploads\/2022\/08\/9b121487-a40d-46b9-a4f7-9c05ab5aef2b-1024x682.jpg 1024w, https:\/\/saoluiz.uri.br\/wordpress\/wp-content\/uploads\/2022\/08\/9b121487-a40d-46b9-a4f7-9c05ab5aef2b-768x512.jpg 768w, https:\/\/saoluiz.uri.br\/wordpress\/wp-content\/uploads\/2022\/08\/9b121487-a40d-46b9-a4f7-9c05ab5aef2b.jpg 1280w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/saoluiz.uri.br\/wordpress\/wp-content\/uploads\/2022\/08\/769dd82a-8aa5-4661-bd88-a3ead274ec9b.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/saoluiz.uri.br\/wordpress\/wp-content\/uploads\/2022\/08\/769dd82a-8aa5-4661-bd88-a3ead274ec9b-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/saoluiz.uri.br\/wordpress\/wp-content\/uploads\/2022\/08\/769dd82a-8aa5-4661-bd88-a3ead274ec9b-300x200.jpg 300w, https:\/\/saoluiz.uri.br\/wordpress\/wp-content\/uploads\/2022\/08\/769dd82a-8aa5-4661-bd88-a3ead274ec9b-1024x682.jpg 1024w, https:\/\/saoluiz.uri.br\/wordpress\/wp-content\/uploads\/2022\/08\/769dd82a-8aa5-4661-bd88-a3ead274ec9b-768x512.jpg 768w, https:\/\/saoluiz.uri.br\/wordpress\/wp-content\/uploads\/2022\/08\/769dd82a-8aa5-4661-bd88-a3ead274ec9b.jpg 1280w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/saoluiz.uri.br\/wordpress\/wp-content\/uploads\/2022\/08\/fdd4e4be-76bf-42de-9eea-ba7807749b35.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/saoluiz.uri.br\/wordpress\/wp-content\/uploads\/2022\/08\/fdd4e4be-76bf-42de-9eea-ba7807749b35-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/saoluiz.uri.br\/wordpress\/wp-content\/uploads\/2022\/08\/fdd4e4be-76bf-42de-9eea-ba7807749b35-300x200.jpg 300w, https:\/\/saoluiz.uri.br\/wordpress\/wp-content\/uploads\/2022\/08\/fdd4e4be-76bf-42de-9eea-ba7807749b35-1024x682.jpg 1024w, https:\/\/saoluiz.uri.br\/wordpress\/wp-content\/uploads\/2022\/08\/fdd4e4be-76bf-42de-9eea-ba7807749b35-768x512.jpg 768w, https:\/\/saoluiz.uri.br\/wordpress\/wp-content\/uploads\/2022\/08\/fdd4e4be-76bf-42de-9eea-ba7807749b35.jpg 1280w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/saoluiz.uri.br\/wordpress\/wp-content\/uploads\/2022\/08\/af8aefa8-62ce-430c-bd92-bc94551cd296.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/saoluiz.uri.br\/wordpress\/wp-content\/uploads\/2022\/08\/af8aefa8-62ce-430c-bd92-bc94551cd296-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/saoluiz.uri.br\/wordpress\/wp-content\/uploads\/2022\/08\/af8aefa8-62ce-430c-bd92-bc94551cd296-300x200.jpg 300w, https:\/\/saoluiz.uri.br\/wordpress\/wp-content\/uploads\/2022\/08\/af8aefa8-62ce-430c-bd92-bc94551cd296-1024x682.jpg 1024w, https:\/\/saoluiz.uri.br\/wordpress\/wp-content\/uploads\/2022\/08\/af8aefa8-62ce-430c-bd92-bc94551cd296-768x512.jpg 768w, https:\/\/saoluiz.uri.br\/wordpress\/wp-content\/uploads\/2022\/08\/af8aefa8-62ce-430c-bd92-bc94551cd296.jpg 1280w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>Em 15 de agosto de 2022, ocorreu, no Sal\u00e3o de Atos da URI &#8211; S\u00e3o Luiz Gonzaga, evento promovido pela ESA-RS e pela OAB, Subse\u00e7\u00e3o local, com apoio do Curso de Direito. Tratou-se da palestra de t\u00edtulo &#8220;Os desafios da advocacia frente \u00e0 adequa\u00e7\u00e3o da Lei Geral de Prote\u00e7\u00e3o de Dados no Brasil&#8221;, proferida por [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":21122,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,15,4,165,1],"tags":[],"class_list":["post-21112","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaques","category-direito","category-graduacao","category-graduacao-10documentos","category-noticias"],"_links":{"self":[{"href":"https:\/\/saoluiz.uri.br\/wordpress\/index.php\/wp-json\/wp\/v2\/posts\/21112","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/saoluiz.uri.br\/wordpress\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/saoluiz.uri.br\/wordpress\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/saoluiz.uri.br\/wordpress\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/saoluiz.uri.br\/wordpress\/index.php\/wp-json\/wp\/v2\/comments?post=21112"}],"version-history":[{"count":1,"href":"https:\/\/saoluiz.uri.br\/wordpress\/index.php\/wp-json\/wp\/v2\/posts\/21112\/revisions"}],"predecessor-version":[{"id":21125,"href":"https:\/\/saoluiz.uri.br\/wordpress\/index.php\/wp-json\/wp\/v2\/posts\/21112\/revisions\/21125"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/saoluiz.uri.br\/wordpress\/index.php\/wp-json\/wp\/v2\/media\/21122"}],"wp:attachment":[{"href":"https:\/\/saoluiz.uri.br\/wordpress\/index.php\/wp-json\/wp\/v2\/media?parent=21112"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/saoluiz.uri.br\/wordpress\/index.php\/wp-json\/wp\/v2\/categories?post=21112"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/saoluiz.uri.br\/wordpress\/index.php\/wp-json\/wp\/v2\/tags?post=21112"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}