{"id":20137,"date":"2022-05-13T21:08:44","date_gmt":"2022-05-14T00:08:44","guid":{"rendered":"https:\/\/saoluiz.uri.br\/wordpress\/?p=20137"},"modified":"2022-05-13T21:08:44","modified_gmt":"2022-05-14T00:08:44","slug":"realizada-aula-inaugural-do-modulo-ii-dos-cursos-ead-da-uri","status":"publish","type":"post","link":"https:\/\/saoluiz.uri.br\/wordpress\/index.php\/2022\/05\/13\/realizada-aula-inaugural-do-modulo-ii-dos-cursos-ead-da-uri\/","title":{"rendered":"Realizada Aula Inaugural do M\u00f3dulo II dos Cursos EAD da URI"},"content":{"rendered":"<p>Foi realizada nesta sexta-feira, 13, a Aula Inaugural do M\u00f3dulo II dos Cursos EAD da URI. Os professores Leandro Langoski (Erechim), Manuele Duarte (Erechim) Juliana do Nascimento Antes (S\u00e3o Luiz Gonzaga) e J\u00fanior Luiz de Souza (Erechim) mediaram a conversa com os alunos ingressantes.<\/p>\n<p>O encontro teve o objetivo de apresentar e explicar a plataforma blackboard, ambiente virtual utilizado pelos estudantes. Tamb\u00e9m houve espa\u00e7o para retiradas de d\u00favidas.<\/p>\n<p>Ao longo do ano s\u00e3o quatro M\u00f3dulos. Aqueles que desejam ingressar em um dos Cursos EAD da URI iniciam sua forma\u00e7\u00e3o no in\u00edcio destas etapas. O M\u00f3dulo II, por exemplo, iniciou no dia 9.<\/p>\n<div id='gallery-1' class='gallery galleryid-20137 gallery-columns-1 gallery-size-medium'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/saoluiz.uri.br\/wordpress\/wp-content\/uploads\/2022\/05\/805c43dd-5ed8-4e6a-bc4d-3eda29bcacf4.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"209\" src=\"https:\/\/saoluiz.uri.br\/wordpress\/wp-content\/uploads\/2022\/05\/805c43dd-5ed8-4e6a-bc4d-3eda29bcacf4-300x209.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/saoluiz.uri.br\/wordpress\/wp-content\/uploads\/2022\/05\/805c43dd-5ed8-4e6a-bc4d-3eda29bcacf4-300x209.jpg 300w, https:\/\/saoluiz.uri.br\/wordpress\/wp-content\/uploads\/2022\/05\/805c43dd-5ed8-4e6a-bc4d-3eda29bcacf4-1024x713.jpg 1024w, https:\/\/saoluiz.uri.br\/wordpress\/wp-content\/uploads\/2022\/05\/805c43dd-5ed8-4e6a-bc4d-3eda29bcacf4-768x534.jpg 768w, https:\/\/saoluiz.uri.br\/wordpress\/wp-content\/uploads\/2022\/05\/805c43dd-5ed8-4e6a-bc4d-3eda29bcacf4.jpg 1243w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/saoluiz.uri.br\/wordpress\/wp-content\/uploads\/2022\/05\/b899636e-c775-4a5e-918b-6e5db182705d.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/saoluiz.uri.br\/wordpress\/wp-content\/uploads\/2022\/05\/b899636e-c775-4a5e-918b-6e5db182705d-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/saoluiz.uri.br\/wordpress\/wp-content\/uploads\/2022\/05\/b899636e-c775-4a5e-918b-6e5db182705d-300x225.jpg 300w, https:\/\/saoluiz.uri.br\/wordpress\/wp-content\/uploads\/2022\/05\/b899636e-c775-4a5e-918b-6e5db182705d-1024x767.jpg 1024w, https:\/\/saoluiz.uri.br\/wordpress\/wp-content\/uploads\/2022\/05\/b899636e-c775-4a5e-918b-6e5db182705d-768x576.jpg 768w, https:\/\/saoluiz.uri.br\/wordpress\/wp-content\/uploads\/2022\/05\/b899636e-c775-4a5e-918b-6e5db182705d.jpg 1265w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/saoluiz.uri.br\/wordpress\/wp-content\/uploads\/2022\/05\/d86e87d4-873b-477c-b3ac-2d3188ae73c0.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"210\" src=\"https:\/\/saoluiz.uri.br\/wordpress\/wp-content\/uploads\/2022\/05\/d86e87d4-873b-477c-b3ac-2d3188ae73c0-300x210.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/saoluiz.uri.br\/wordpress\/wp-content\/uploads\/2022\/05\/d86e87d4-873b-477c-b3ac-2d3188ae73c0-300x210.jpg 300w, https:\/\/saoluiz.uri.br\/wordpress\/wp-content\/uploads\/2022\/05\/d86e87d4-873b-477c-b3ac-2d3188ae73c0-1024x717.jpg 1024w, https:\/\/saoluiz.uri.br\/wordpress\/wp-content\/uploads\/2022\/05\/d86e87d4-873b-477c-b3ac-2d3188ae73c0-768x537.jpg 768w, https:\/\/saoluiz.uri.br\/wordpress\/wp-content\/uploads\/2022\/05\/d86e87d4-873b-477c-b3ac-2d3188ae73c0.jpg 1246w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>Foi realizada nesta sexta-feira, 13, a Aula Inaugural do M\u00f3dulo II dos Cursos EAD da URI. Os professores Leandro Langoski (Erechim), Manuele Duarte (Erechim) Juliana do Nascimento Antes (S\u00e3o Luiz Gonzaga) e J\u00fanior Luiz de Souza (Erechim) mediaram a conversa com os alunos ingressantes. O encontro teve o objetivo de apresentar e explicar a plataforma [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":20147,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,155,1],"tags":[],"class_list":["post-20137","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaques","category-ead-uri","category-noticias"],"_links":{"self":[{"href":"https:\/\/saoluiz.uri.br\/wordpress\/index.php\/wp-json\/wp\/v2\/posts\/20137","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/saoluiz.uri.br\/wordpress\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/saoluiz.uri.br\/wordpress\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/saoluiz.uri.br\/wordpress\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/saoluiz.uri.br\/wordpress\/index.php\/wp-json\/wp\/v2\/comments?post=20137"}],"version-history":[{"count":1,"href":"https:\/\/saoluiz.uri.br\/wordpress\/index.php\/wp-json\/wp\/v2\/posts\/20137\/revisions"}],"predecessor-version":[{"id":20149,"href":"https:\/\/saoluiz.uri.br\/wordpress\/index.php\/wp-json\/wp\/v2\/posts\/20137\/revisions\/20149"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/saoluiz.uri.br\/wordpress\/index.php\/wp-json\/wp\/v2\/media\/20147"}],"wp:attachment":[{"href":"https:\/\/saoluiz.uri.br\/wordpress\/index.php\/wp-json\/wp\/v2\/media?parent=20137"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/saoluiz.uri.br\/wordpress\/index.php\/wp-json\/wp\/v2\/categories?post=20137"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/saoluiz.uri.br\/wordpress\/index.php\/wp-json\/wp\/v2\/tags?post=20137"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}