{"id":17981,"date":"2021-04-23T14:29:53","date_gmt":"2021-04-23T17:29:53","guid":{"rendered":"https:\/\/saoluiz.uri.br\/wordpress\/?p=17981"},"modified":"2021-04-23T14:29:53","modified_gmt":"2021-04-23T17:29:53","slug":"disciplina-de-ciencias-e-tecnologia-de-materiais-do-curso-de-engenharia-eletrica-teve-participacao-de-profissional-da-area-de-engenharia-civil","status":"publish","type":"post","link":"https:\/\/saoluiz.uri.br\/wordpress\/index.php\/2021\/04\/23\/disciplina-de-ciencias-e-tecnologia-de-materiais-do-curso-de-engenharia-eletrica-teve-participacao-de-profissional-da-area-de-engenharia-civil\/","title":{"rendered":"Disciplina de Ci\u00eancias e Tecnologia de Materiais do curso de Engenharia El\u00e9trica teve participa\u00e7\u00e3o de profissional da \u00e1rea de Engenharia Civil"},"content":{"rendered":"<p>Na noite do dia 14 de abril, a turma do 3\u00ba Semestre, na disciplina Ci\u00eancias e Tecnologia de Materiais do curso de Engenharia El\u00e9trica, recebeu &#8211; para compartilhar seus conhecimentos, a Engenheira Civil, Larissa Pisoni Gelatti, da empresa Mega Sul Concretos Ltda. A referida disciplina \u00e9 ministrada pela professora Neiva Almeida dos Santos que tem como conceito principal na ementa, os diferentes tipos de materiais. Na ocasi\u00e3o, Larissa Pisoni Gelatti falou sobre os diferentes tipos de materiais, elencando o alum\u00ednio, a\u00e7o e porcelanato, bem como, a import\u00e2ncia do Engenheiro Eletricista na constru\u00e7\u00e3o civil, como projetista e executor de obras de pequeno e grande porte. Nosso agradecimento aos alunos que participaram e a palestrante que enalteceram nossa atividade, mesmo de forma remota fazem a diferen\u00e7a.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Na noite do dia 14 de abril, a turma do 3\u00ba Semestre, na disciplina Ci\u00eancias e Tecnologia de Materiais do curso de Engenharia El\u00e9trica, recebeu &#8211; para compartilhar seus conhecimentos, a Engenheira Civil, Larissa Pisoni Gelatti, da empresa Mega Sul Concretos Ltda. A referida disciplina \u00e9 ministrada pela professora Neiva Almeida dos Santos que tem [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":17982,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17,1],"tags":[],"class_list":["post-17981","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-engenharia-eletrica","category-noticias"],"_links":{"self":[{"href":"https:\/\/saoluiz.uri.br\/wordpress\/index.php\/wp-json\/wp\/v2\/posts\/17981","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/saoluiz.uri.br\/wordpress\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/saoluiz.uri.br\/wordpress\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/saoluiz.uri.br\/wordpress\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/saoluiz.uri.br\/wordpress\/index.php\/wp-json\/wp\/v2\/comments?post=17981"}],"version-history":[{"count":1,"href":"https:\/\/saoluiz.uri.br\/wordpress\/index.php\/wp-json\/wp\/v2\/posts\/17981\/revisions"}],"predecessor-version":[{"id":17983,"href":"https:\/\/saoluiz.uri.br\/wordpress\/index.php\/wp-json\/wp\/v2\/posts\/17981\/revisions\/17983"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/saoluiz.uri.br\/wordpress\/index.php\/wp-json\/wp\/v2\/media\/17982"}],"wp:attachment":[{"href":"https:\/\/saoluiz.uri.br\/wordpress\/index.php\/wp-json\/wp\/v2\/media?parent=17981"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/saoluiz.uri.br\/wordpress\/index.php\/wp-json\/wp\/v2\/categories?post=17981"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/saoluiz.uri.br\/wordpress\/index.php\/wp-json\/wp\/v2\/tags?post=17981"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}