{"id":17715,"date":"2021-03-01T17:03:12","date_gmt":"2021-03-01T20:03:12","guid":{"rendered":"https:\/\/saoluiz.uri.br\/wordpress\/?p=17715"},"modified":"2021-03-01T17:24:31","modified_gmt":"2021-03-01T20:24:31","slug":"divulgado-o-resultado-do-processo-seletivo-de-estagiarios-para-o-balcao-do-consumidor-2","status":"publish","type":"post","link":"https:\/\/saoluiz.uri.br\/wordpress\/index.php\/2021\/03\/01\/divulgado-o-resultado-do-processo-seletivo-de-estagiarios-para-o-balcao-do-consumidor-2\/","title":{"rendered":"Divulgado o resultado do Processo Seletivo de Estagi\u00e1rios para o Balc\u00e3o do Consumidor"},"content":{"rendered":"<p>A Coordenadora do Curso de Direito da Universidade Regional Integrada do Alto Uruguai e das Miss\u00f5es, Campus S\u00e3o Luiz Gonzaga, torna p\u00fablico o resultado do Processo Seletivo de Estagi\u00e1rios para o Balc\u00e3o do Consumidor, conforme Edital 01\/2021.<\/p>\n<p><strong>Link: <a href=\"https:\/\/saoluiz.uri.br\/wordpress\/wp-content\/uploads\/2021\/03\/Untitled_20210301_161535.pdf\">Acesse o resultado aqui<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Coordenadora do Curso de Direito da Universidade Regional Integrada do Alto Uruguai e das Miss\u00f5es, Campus S\u00e3o Luiz Gonzaga, torna p\u00fablico o resultado do Processo Seletivo de Estagi\u00e1rios para o Balc\u00e3o do Consumidor, conforme Edital 01\/2021. Link: Acesse o resultado aqui<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[23,15,1],"tags":[],"class_list":["post-17715","post","type-post","status-publish","format-standard","hentry","category-3editais","category-direito","category-noticias"],"_links":{"self":[{"href":"https:\/\/saoluiz.uri.br\/wordpress\/index.php\/wp-json\/wp\/v2\/posts\/17715","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/saoluiz.uri.br\/wordpress\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/saoluiz.uri.br\/wordpress\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/saoluiz.uri.br\/wordpress\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/saoluiz.uri.br\/wordpress\/index.php\/wp-json\/wp\/v2\/comments?post=17715"}],"version-history":[{"count":1,"href":"https:\/\/saoluiz.uri.br\/wordpress\/index.php\/wp-json\/wp\/v2\/posts\/17715\/revisions"}],"predecessor-version":[{"id":17717,"href":"https:\/\/saoluiz.uri.br\/wordpress\/index.php\/wp-json\/wp\/v2\/posts\/17715\/revisions\/17717"}],"wp:attachment":[{"href":"https:\/\/saoluiz.uri.br\/wordpress\/index.php\/wp-json\/wp\/v2\/media?parent=17715"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/saoluiz.uri.br\/wordpress\/index.php\/wp-json\/wp\/v2\/categories?post=17715"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/saoluiz.uri.br\/wordpress\/index.php\/wp-json\/wp\/v2\/tags?post=17715"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}